{"id":28588,"date":"2023-09-27T18:50:32","date_gmt":"2023-09-27T10:50:32","guid":{"rendered":"https:\/\/www.konmison.com\/?p=28588"},"modified":"2023-09-28T18:13:22","modified_gmt":"2023-09-28T10:13:22","slug":"feierliches-herbstfest-konmisons-freudiges-traditionelles-jubilaum","status":"publish","type":"post","link":"https:\/\/www.konmison.com\/de\/feierliches-herbstfest-konmisons-freudiges-traditionelles-jubilaum\/","title":{"rendered":"Das Mittherbstfest feiern: Konmison's freudiger traditioneller Jubel"},"content":{"rendered":"<p>Am 27. September fand im Konmison-B\u00fcro eine besondere Veranstaltung zur Feier des chinesischen Mittherbstfestes statt. Inspiriert von beliebten traditionellen Spielen und mit spannenden Preisen kamen die Mitarbeiter von Konmison zusammen, um diesen Anlass mit Freude zu feiern.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.konmison.com\/wp-content\/uploads\/2023\/09\/2023Mid-Autumn-3.jpg\" alt=\"2023Mitte Herbst 3\" class=\"wp-image-28591\" width=\"750\" height=\"500\"\/><figcaption>Konmison-Mitglieder stehen vor den von ihnen bevorzugten Spielstationen Schlange<\/figcaption><\/figure>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Das j\u00e4hrliche Mittherbstfest, liebevoll Mondfest genannt, ist eine gesch\u00e4tzte Tradition, die durch Familientreffen und das genussvolle Teilen von Mondkuchen gekennzeichnet ist. Dieses herzliche Fest f\u00e4llt auf den 15. Tag des achten Monats des chinesischen Mondkalenders, der mit der vollsten und strahlendsten Phase des Mondes zusammenf\u00e4llt. Dieses Jahr f\u00e4llt es auf den 29. September.<\/p>\n\n\n\n<p>Die Feierlichkeiten begannen mit der Darbietung beliebter Melodien, die mit dem Mittherbstfest verbunden sind. Die begeisterten Teilnehmer standen eifrig Schlange vor den von ihnen bevorzugten Spielstationen. Es gab drei Hauptaktivit\u00e4ten:<\/p>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\ud83c\udf68 <strong>Herstellung von Bingfen (Eispulver-Gelee):<\/strong>&nbsp;Die Leute versuchten sich an der Herstellung ihres eigenen Bingfen, auch bekannt als Eispulver-Gelee. Diese k\u00f6stliche Delikatesse nimmt bei den Feierlichkeiten zum Mittherbstfest einen besonderen Platz ein und bietet einen erfrischenden Kontrast zur Reichhaltigkeit der Mondkuchen. Seine k\u00fchle, wohltuende Ausstrahlung wird besonders in Guangzhou gesch\u00e4tzt, wo hei\u00dfe Sommertage andauern, so dass es der perfekte Genuss ist, um die Hitze zu vertreiben.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.konmison.com\/wp-content\/uploads\/2023\/09\/2023Mid-Autumn-1.jpg\" alt=\"2023Mitte Herbst 1\" class=\"wp-image-28592\" width=\"750\" height=\"500\"\/><figcaption>Handwerkliche T\u00e4tigkeit in Bingfen<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.konmison.com\/wp-content\/uploads\/2023\/09\/2023Mid-Autumn-9.jpg\" alt=\"2023Mitte Herbst 9\" class=\"wp-image-28689\" width=\"750\" height=\"500\"\/><figcaption>Bingfen basteln - die Menschen stellen ihren eigenen Bingfen mit ihren bevorzugten Lebensmitteln her<\/figcaption><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\ud83c\udfaf <strong>Touhu Challenge (Pitch-Pot-Spiel):<\/strong>&nbsp;Das Touhu- oder Pitch-Pot-Spiel f\u00fcgte ein Element des freundschaftlichen Wettbewerbs hinzu. Die Spieler versuchten, Gegenst\u00e4nde in die daf\u00fcr vorgesehenen Beh\u00e4lter zu werfen - ein klassisches Spiel, das den fr\u00f6hlichen Geist des Festivals widerspiegelt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.konmison.com\/wp-content\/uploads\/2023\/09\/2023Mid-Autumn-7.jpg\" alt=\"2023Mitte Herbst 7\" class=\"wp-image-28690\" width=\"750\" height=\"500\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.konmison.com\/wp-content\/uploads\/2023\/09\/2023Mid-Autumn-6.jpg\" alt=\"2023Mitte Herbst 6\" class=\"wp-image-28691\" width=\"750\" height=\"500\"\/><\/figure>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\ud83c\udfee <strong>Laternen-R\u00e4tsel:<\/strong>&nbsp;Der Tradition folgend waren auch die Laternenr\u00e4tsel ein zentraler Bestandteil der Feier. Die Teilnehmer besch\u00e4ftigten sich mit dem zeitlosen Brauch, R\u00e4tsel zu l\u00f6sen, die an Laternen befestigt sind - eine reizvolle geistige Herausforderung in dieser Zeit der Besinnung.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.konmison.com\/wp-content\/uploads\/2023\/09\/2023Mid-Autumn-8-1.jpg\" alt=\"2023Mitte Herbst 8 1\" class=\"wp-image-28692\" width=\"750\" height=\"500\"\/><\/figure>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Als das Lachen unserer Teammitglieder durch das Konmison-B\u00fcro hallte, war klar, dass unsere Mittherbstfestfeier einen bleibenden Eindruck hinterlassen hatte. Durch die traditionellen Spiele und die gemeinsamen Momente haben wir sch\u00f6ne Erinnerungen geschaffen und uns den Geist der Einheit zu eigen gemacht, den dieses Fest verk\u00f6rpert.<\/p>\n\n\n\n<p>Das Konmison-Team m\u00f6chte Ihnen allen von Herzen alles Gute w\u00fcnschen. M\u00f6ge das Strahlen des Vollmonds Licht in Ihr Leben bringen, und m\u00f6ge die Freude, die wir heute geteilt haben, Ihre Tage das ganze Jahr \u00fcber erhellen. Frohes Mittherbstfest! \ud83c\udf15<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 27. September fand im Konmison-B\u00fcro eine besondere Veranstaltung zur Feier des chinesischen Mittherbstfestes statt. Inspiriert von beliebten traditionellen Spielen und mit spannenden Preisen kamen die Mitarbeiter von Konmison zusammen, um diesen Anlass mit Freude zu feiern.<\/p>","protected":false},"author":3,"featured_media":28686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-28588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/posts\/28588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/comments?post=28588"}],"version-history":[{"count":6,"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/posts\/28588\/revisions"}],"predecessor-version":[{"id":28694,"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/posts\/28588\/revisions\/28694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/media\/28686"}],"wp:attachment":[{"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/media?parent=28588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/categories?post=28588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.konmison.com\/de\/wp-json\/wp\/v2\/tags?post=28588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}