{"id":81,"date":"2022-05-30T10:10:02","date_gmt":"2022-05-30T02:10:02","guid":{"rendered":"https:\/\/www.konmison.com\/?page_id=81"},"modified":"2022-08-17T14:48:20","modified_gmt":"2022-08-17T06:48:20","slug":"faq","status":"publish","type":"page","link":"https:\/\/www.konmison.com\/it\/faq\/","title":{"rendered":"Domande frequenti"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"81\" class=\"elementor elementor-81\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b90f0e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0b90f0e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be7fdd8\" data-id=\"be7fdd8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88a5256 elementor-widget elementor-widget-template\" data-id=\"88a5256\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"295\" class=\"elementor elementor-295\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32659aa7 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"32659aa7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3.6,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3733c9a8\" data-id=\"3733c9a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9702255 elementor-widget elementor-widget-pp-breadcrumbs\" data-id=\"9702255\" data-element_type=\"widget\" data-settings=\"{&quot;breadcrumbs_type&quot;:&quot;powerpack&quot;}\" data-widget_type=\"pp-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"pp-breadcrumbs pp-breadcrumbs-powerpack\">\t\t<li class=\"pp-breadcrumbs-item pp-breadcrumbs-item-home\">\n\t\t\t<a class=\"pp-breadcrumbs-crumb pp-breadcrumbs-crumb-link pp-breadcrumbs-crumb-home\" href=\"https:\/\/www.konmison.com\/it\" title=\"Casa\">\n\t\t\t\t<span class=\"pp-breadcrumbs-text\">\n\t\t\t\t\t\t\t\t\t\tCasa\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li class=\"pp-breadcrumbs-separator\">\t\t\t\t<span class='pp-separator-icon pp-icon'>\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t<\/li><\/ul>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bcdb4fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bcdb4fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7bcb63a1\" data-id=\"7bcb63a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c96319 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"61c96319\" data-element_type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h4&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t<h5 class=\"elementor-toc__header-title\">\n\t\t\t\tIndice dei contenuti\t\t\t<\/h5>\n\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__61c96319\" aria-expanded=\"true\" aria-label=\"Apri l&#039;indice dei contenuti\"><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__61c96319\" aria-expanded=\"true\" aria-label=\"Chiudi l&#039;indice dei contenuti\"><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t<div id=\"elementor-toc__61c96319\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69865eca\" data-id=\"69865eca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6122927a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6122927a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-56ad1c76\" data-id=\"56ad1c76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b42a220 elementor-widget elementor-widget-heading\" data-id=\"4b42a220\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Generale<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34889384 elementor-widget elementor-widget-pp-advanced-accordion\" data-id=\"34889384\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-34889384\" data-accordion-id=\"34889384\">\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-8811\" class=\"pp-accordion-tab-title\" tabindex=\"8811\" data-tab=\"1\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-8811\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tAvete qualche certificazione?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-8811\" class=\"pp-accordion-tab-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-8811\">\n\t\t\t\t\t\t<p>Abbiamo certificati CE, FDA, RoHS, brevetti ecc.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-8812\" class=\"pp-accordion-tab-title\" tabindex=\"8812\" data-tab=\"2\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-8812\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tQual \u00e8 il MOQ?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-8812\" class=\"pp-accordion-tab-content\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-8812\">\n\t\t\t\t\t\t<p>Il MOQ del modello in stock \u00e8 di 5 pezzi.<\/p><p>Per i modelli personalizzati il MOQ \u00e8 di 10-100pz.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f3bbdcf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f3bbdcf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-674cae14\" data-id=\"674cae14\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-278342cd elementor-widget elementor-widget-heading\" data-id=\"278342cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Prodotti<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a8e06b1 elementor-widget elementor-widget-pp-advanced-accordion\" data-id=\"1a8e06b1\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-1a8e06b1\" data-accordion-id=\"1a8e06b1\">\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-4451\" class=\"pp-accordion-tab-title\" tabindex=\"4451\" data-tab=\"1\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-4451\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tIl prodotto sar\u00e0 fragile durante la spedizione?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-4451\" class=\"pp-accordion-tab-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-4451\">\n\t\t\t\t\t\t<p>No, non \u00e8 cos\u00ec. I nostri materiali sono di alta qualit\u00e0 e ogni strumento \u00e8 accuratamente ispezionato dal nostro team di professionisti prima della spedizione. Inoltre, il pacchetto \u00e8 con schiuma cood all'interno della scatola di cartone \/ lega di alluminio \/ scatola di legno, quindi \u00e8 sicuro.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7d4f2fa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d4f2fa6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-750f2045\" data-id=\"750f2045\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab7bfc4 elementor-widget elementor-widget-heading\" data-id=\"7ab7bfc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Personalizzazione<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dacbbe9 elementor-widget elementor-widget-pp-advanced-accordion\" data-id=\"6dacbbe9\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-6dacbbe9\" data-accordion-id=\"6dacbbe9\">\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1841\" class=\"pp-accordion-tab-title\" tabindex=\"1841\" data-tab=\"1\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1841\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tPotreste progettare l'aspetto dei prodotti?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1841\" class=\"pp-accordion-tab-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1841\">\n\t\t\t\t\t\t<p>S\u00ec, i nostri prodotti sono disponibili per essere personalizzati, in quanto disponiamo di un team di ingegneri professionisti di R&amp;S. Inoltre la nostra fabbrica potrebbe aiutare ad aprire lo stampo di conseguenza.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1842\" class=\"pp-accordion-tab-title\" tabindex=\"1842\" data-tab=\"2\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1842\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tPosso inserire il logo privato sui prodotti?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1842\" class=\"pp-accordion-tab-content\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1842\">\n\t\t\t\t\t\t<p>S\u00ec, il logo privato pu\u00f2 essere inserito sullo schermo, stampato sui prodotti o sulle scatole delle confezioni.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1843\" class=\"pp-accordion-tab-title\" tabindex=\"1843\" data-tab=\"3\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1843\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tPosso fare un pacchetto personalizzato?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1843\" class=\"pp-accordion-tab-content\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1843\">\n\t\t\t\t\t\t<p>S\u00ec, il pacchetto pu\u00f2 essere personalizzato, il MOQ della quantit\u00e0 di pacchetto personalizzato sar\u00e0 citato dopo aver controllato il vostro logo.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1844\" class=\"pp-accordion-tab-title\" tabindex=\"1844\" data-tab=\"4\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1844\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tQual \u00e8 il processo OEM\/ODM?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1844\" class=\"pp-accordion-tab-content\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1844\">\n\t\t\t\t\t\t<p>Dopo aver ricevuto le vostre esigenze di personalizzazione, il nostro team di R&amp;S svilupper\u00e0 e poi metter\u00e0 in produzione il prodotto. Dalla progettazione all'assemblaggio e al collaudo, il nostro team di professionisti supervisiona la qualit\u00e0 durante la produzione. Una volta completata la produzione, il prodotto verr\u00e0 imballato e spedito.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6996b951 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6996b951\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7fcd178f\" data-id=\"7fcd178f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ba0584a elementor-widget elementor-widget-heading\" data-id=\"7ba0584a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Servizio<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c9c2aa8 elementor-widget elementor-widget-pp-advanced-accordion\" data-id=\"3c9c2aa8\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-3c9c2aa8\" data-accordion-id=\"3c9c2aa8\">\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1011\" class=\"pp-accordion-tab-title\" tabindex=\"1011\" data-tab=\"1\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1011\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tQual \u00e8 la data di spedizione?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1011\" class=\"pp-accordion-tab-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1011\">\n\t\t\t\t\t\t<p>Di solito 3-10 giorni lavorativi, anche il giorno stesso per alcuni articoli in stock.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1012\" class=\"pp-accordion-tab-title\" tabindex=\"1012\" data-tab=\"2\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1012\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tCosa succede se non so come usare questo strumento?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1012\" class=\"pp-accordion-tab-content\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1012\">\n\t\t\t\t\t\t<p>Forniamo un manuale d'uso completo o un video per le istruzioni e un servizio di consulenza online 24 ore al giorno.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1013\" class=\"pp-accordion-tab-title\" tabindex=\"1013\" data-tab=\"3\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1013\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tOffrite una garanzia?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1013\" class=\"pp-accordion-tab-content\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1013\">\n\t\t\t\t\t\t<p>Offriamo un anno di garanzia per l'host principale a partire dalla data di acquisto (con fattura), e tre mesi di garanzia per le maniglie.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ac1da78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ac1da78\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-559f45e4\" data-id=\"559f45e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29a5b7fb elementor-widget elementor-widget-heading\" data-id=\"29a5b7fb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pagamento<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf26d47 elementor-widget elementor-widget-pp-advanced-accordion\" data-id=\"4bf26d47\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-4bf26d47\" data-accordion-id=\"4bf26d47\">\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1271\" class=\"pp-accordion-tab-title\" tabindex=\"1271\" data-tab=\"1\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1271\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tQuali sono i termini e le modalit\u00e0 di pagamento?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1271\" class=\"pp-accordion-tab-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1271\">\n\t\t\t\t\t\t<p>Pagamento inferiore a US$5000, 100% in anticipo. Pagamento superiore a US$5000, 30% di deposito in anticipo e 70% di saldo prima della consegna.<\/p><p>Per i modi di pagamento, T\/T, Western Union, L\/C o Paypal. Questo \u00e8 negoziabile.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-22cea377 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22cea377\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3a662c03\" data-id=\"3a662c03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34a7a4ea elementor-widget elementor-widget-heading\" data-id=\"34a7a4ea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Spedizione<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50b1d5db elementor-widget elementor-widget-pp-advanced-accordion\" data-id=\"50b1d5db\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-50b1d5db\" data-accordion-id=\"50b1d5db\">\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"pp-accordion-tab-title-1351\" class=\"pp-accordion-tab-title\" tabindex=\"1351\" data-tab=\"1\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1351\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\tQual \u00e8 il vostro metodo di spedizione?\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-up\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1351\" class=\"pp-accordion-tab-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1351\">\n\t\t\t\t\t\t<p>I pacchi di piccole dimensioni normali vengono spediti tramite espresso internazionale, come DHL, UPS, FEDEX, TNT e EMS ecc.<\/p><p>Per gli ordini di grandi dimensioni saranno inviati tramite trasporto aereo, trasporto terrestre o trasporto marittimo.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f87346 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2f87346\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad07823\" data-id=\"ad07823\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a14be6f elementor-widget elementor-widget-template\" data-id=\"a14be6f\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"409\" class=\"elementor elementor-409\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76a2c331 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76a2c331\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28a0d243\" data-id=\"28a0d243\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75afcfbb elementor-widget elementor-widget-heading\" data-id=\"75afcfbb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Promuovere l'attivit\u00e0 di bellezza con la tecnologia Konmison<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79548be4 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"79548be4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Per i proprietari di marchi\/grossisti\/commercianti<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Per le aziende di prodotti per la pelle<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Per saloni di bellezza\/cliniche\/centri benessere<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4da3b52f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4da3b52f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM0NCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contatto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Indice Generale Avete delle certificazioni? Abbiamo certificati CE, FDA, RoHS, brevetti ecc. Qual \u00e8 il MOQ? Il MOQ del modello di stock \u00e8 di 5 pezzi. Per i modelli personalizzati il MOQ \u00e8 di 10-100 pezzi. Prodotti Il prodotto sar\u00e0 fragile durante la spedizione? No, non lo sar\u00e0. I nostri materiali sono di alta qualit\u00e0 e ogni strumento \u00e8 accuratamente ispezionato dal nostro team di professionisti prima [...]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Frequently-asked Questions | Konmison","_seopress_titles_desc":"From beauty treatments to business benefits, our FAQ section answers common questions about our machinery and process, to ensure beauty brands meet any challenge.","_seopress_robots_index":"","footnotes":""},"class_list":["post-81","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/pages\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/comments?post=81"}],"version-history":[{"count":44,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/pages\/81\/revisions"}],"predecessor-version":[{"id":3274,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/pages\/81\/revisions\/3274"}],"wp:attachment":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/media?parent=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}