{"id":8696,"date":"2022-10-26T16:40:29","date_gmt":"2022-10-26T08:40:29","guid":{"rendered":"https:\/\/www.konmison.com\/?p=8696"},"modified":"2022-10-31T16:06:24","modified_gmt":"2022-10-31T08:06:24","slug":"corriamo-al-meeting-sportivo-dautunno","status":"publish","type":"post","link":"https:\/\/www.konmison.com\/it\/corriamo-al-meeting-sportivo-dautunno\/","title":{"rendered":"Corriamo al meeting sportivo d'autunno"},"content":{"rendered":"<p>Per arricchire il tempo libero dei dipendenti e migliorare la loro forma fisica, la nostra azienda organizza spesso alcune attivit\u00e0. Questa volta la nostra azienda ha lanciato l'incontro sportivo autunnale. L'intera azienda \u00e8 stata divisa in 8 squadre e ha organizzato sport interessanti come gare di basket, gare di corsa, gare a ostacoli, staffette, palleggi e cos\u00ec via. All'inizio dell'autunno, nel campo da gioco si sono sentiti incitamenti, incitamenti e grida feroci.<\/p>\n\n\n\n<p>Questo divertente incontro sportivo ha ridotto efficacemente le distanze tra i colleghi, ha rafforzato la coesione dell'azienda, ha migliorato l'entusiasmo dei dipendenti nel partecipare alle attivit\u00e0 e ha migliorato la comunicazione tra i reparti. \u00c8 stato un metodo per creare amicizia e mostrare i propri talenti. In questo modo, abbiamo raggiunto sia la civilt\u00e0 spirituale che i risultati sportivi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00c8 interessante vedere che l'incontro sportivo \u00e8 stato pi\u00f9 divertente e pi\u00f9 innocente. I colleghi hanno sperimentato la gioia dello sport, la gioia della competizione e la gioia della partecipazione. Coltivare la consapevolezza delle regole e lo spirito di cooperazione e stimolare il potenziale dello sport. Non si \u00e8 trattato solo di una revisione della qualit\u00e0 psicologica, della qualit\u00e0 fisica e del livello sportivo dei dipendenti, ma anche di una revisione della disciplina organizzativa e della prospettiva spirituale.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Questi divertenti Giochi si sono conclusi tra gli applausi, ma l'alto spirito di collettivismo mostrato dagli atleti e dal personale dei Giochi, in particolare dagli arbitri, durante questo periodo sar\u00e0 un esempio per noi. Corriamo verso l'obiettivo di \"pi\u00f9 in alto, pi\u00f9 veloce, pi\u00f9 forte\".<\/p>","protected":false},"excerpt":{"rendered":"<p>L'intera azienda \u00e8 stata divisa in 8 squadre e ha organizzato sport interessanti come gare di pallacanestro, gare di corsa, gare a ostacoli, staffette, palleggi e cos\u00ec via.<\/p>","protected":false},"author":3,"featured_media":8698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-8696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/posts\/8696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/comments?post=8696"}],"version-history":[{"count":5,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/posts\/8696\/revisions"}],"predecessor-version":[{"id":9076,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/posts\/8696\/revisions\/9076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/media\/8698"}],"wp:attachment":[{"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/media?parent=8696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/categories?post=8696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.konmison.com\/it\/wp-json\/wp\/v2\/tags?post=8696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}